{"id":4726,"date":"2023-11-02T20:00:48","date_gmt":"2023-11-02T20:00:48","guid":{"rendered":"https:\/\/demo.clutchcreativeco.com\/cosana\/strains\/ketama-2\/"},"modified":"2023-11-08T15:16:50","modified_gmt":"2023-11-08T15:16:50","slug":"purple-punch","status":"publish","type":"strains","link":"https:\/\/demo.clutchcreativeco.com\/cosana\/strains\/purple-punch\/","title":{"rendered":"Purple Punch"},"template":"","strain-type":[37],"class_list":["post-4726","strains","type-strains","status-publish","hentry","strain-type-hybrid"],"_links":{"self":[{"href":"https:\/\/demo.clutchcreativeco.com\/cosana\/wp-json\/wp\/v2\/strains\/4726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/demo.clutchcreativeco.com\/cosana\/wp-json\/wp\/v2\/strains"}],"about":[{"href":"https:\/\/demo.clutchcreativeco.com\/cosana\/wp-json\/wp\/v2\/types\/strains"}],"wp:attachment":[{"href":"https:\/\/demo.clutchcreativeco.com\/cosana\/wp-json\/wp\/v2\/media?parent=4726"}],"wp:term":[{"taxonomy":"strain-type","embeddable":true,"href":"https:\/\/demo.clutchcreativeco.com\/cosana\/wp-json\/wp\/v2\/strain-type?post=4726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}